{"id":12001,"date":"2023-12-18T22:58:41","date_gmt":"2023-12-19T01:58:41","guid":{"rendered":"https:\/\/auna.com.br\/auna\/?p=12001"},"modified":"2024-03-02T10:22:30","modified_gmt":"2024-03-02T13:22:30","slug":"o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia","status":"publish","type":"post","link":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/","title":{"rendered":"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia."},"content":{"rendered":"\n<p>Gest\u00e3o metrol\u00f3gica \u00e9 definida na NBR ISO 10012 como o &#8220;<em>conjunto de elementos inter-relacionados e interativos, necess\u00e1rios para obter a comprova\u00e7\u00e3o metrol\u00f3gica e o controle cont\u00ednuo dos processos de medi\u00e7\u00e3o.<\/em>&#8220;<\/p>\n\n\n\n<p>A gest\u00e3o metrol\u00f3gica possui tr\u00eas pilares sendo:<\/p>\n\n\n\n<p><strong>1- Requisitos metrol\u00f3gicos do cliente ou RMC<\/strong> &#8211; Os requisitos metrol\u00f3gicos do cliente est\u00e3o relacionados ao processo de fabrica\u00e7\u00e3o e\/ou produ\u00e7\u00e3o que garantem conformidade ao produto. Um exemplo \u00e9 o crit\u00e9rio de aceita\u00e7\u00e3o do que esta sendo produzido. <\/p>\n\n\n\n<p><strong>2- Caracter\u00edsticas metrol\u00f3gicas do instrumento de medi\u00e7\u00e3o ou CMEDM<\/strong> &#8211; Caracter\u00edsticas metrol\u00f3gicas dos instrumentos de medi\u00e7\u00e3o. Est\u00e1 relacionada as caracter\u00edsticas t\u00e9cnicas do instrumento como faixa de medi\u00e7\u00e3o, resolu\u00e7\u00e3o, valor de uma divis\u00e3o, histerese, estabilidade, erro, incerteza da medi\u00e7\u00e3o entre diversos outros em fun\u00e7\u00e3o do tipo de instrumento.<\/p>\n\n\n\n<p><strong>3- Verifica\u00e7\u00e3o e comprova\u00e7\u00e3o de metrol\u00f3gica<\/strong> &#8211; Basicamente, a verifica\u00e7\u00e3o e comprova\u00e7\u00e3o metrol\u00f3gica nada mais \u00e9 que, verificar se o instrumento de medi\u00e7\u00e3o possui as caracter\u00edsticas metrol\u00f3gicas necess\u00e1rias para efetuar a medi\u00e7\u00e3o em um determinado ponto do processo de forma a controlar e quando poss\u00edvel garantir se o que est\u00e1 sendo produzido estar\u00e1 dentro do crit\u00e9rio de aceita\u00e7\u00e3o determinado para o produto.<\/p>\n\n\n\n<p>A &#8220;dificuldade&#8221; est\u00e1 justamente neste ponto. Todo e qualquer processo possui varia\u00e7\u00f5es as quais possui, entre outras caracter\u00edsticas, uma incerteza e que via de regra, n\u00e3o \u00e9 determinada pela empresa, ou seja, s\u00e3o determinados crit\u00e9rios de aceita\u00e7\u00e3o sem determinar a incerteza do processo. O mesmo para o instrumento de medi\u00e7\u00e3o onde raramente, h\u00e1 uma efetiva verifica\u00e7\u00e3o quanto a conformidade das caracter\u00edsticas metrol\u00f3gicas do instrumento com rela\u00e7\u00e3o a processo.<\/p>\n\n\n\n<p>E ai vai um ponto importe. O que as empresas normalmente fazem \u00e9 avaliar se o erro mais a incerteza \u00e9 inferior ou igual a um ter\u00e7o do crit\u00e9rio de aceita\u00e7\u00e3o do processo. S\u00f3 que isso \u00e9 um risco.<\/p>\n\n\n\n<p>Vamos verificar os exemplos abaixo onde temos a linha em vermelho representando o processo e a linha em azul representando o instrumento de medi\u00e7\u00e3o. Os limites de cada linha representa o crit\u00e9rio de aceita\u00e7\u00e3o do produto com rela\u00e7\u00e3o a um valor nominal e a incerteza da medi\u00e7\u00e3o do instrumento respectivamente.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao-1024x576.jpg\" alt=\"\" class=\"wp-image-12098\" style=\"width:621px;height:auto\" srcset=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao-1024x576.jpg 1024w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao-300x169.jpg 300w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao-768x432.jpg 768w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao-1536x864.jpg 1536w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao-600x338.jpg 600w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-Sistema-de-gestao-medicao.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Vamos entender considerando que, o erro mais a incerteza da medi\u00e7\u00e3o \u00e9 igual ou inferior a 1\/3 dos limites do processo.<\/p>\n\n\n\n<p><strong>1\u00b0 caso <\/strong>&#8211; Temos o erro do instrumento posicionado pr\u00f3ximo ao valor nominal do processo com a sua incerteza dentro do crit\u00e9rio de aceita\u00e7\u00e3o. Neste caso, n\u00e3o temos grandes problemas uma vez que a incerteza do instrumento de medi\u00e7\u00e3o esta afastado dos limites do processo.<\/p>\n\n\n\n<p><strong>2\u00b0 caso <\/strong>&#8211; Temos um instrumento com o erro de medi\u00e7\u00e3o elevado com a sua incerteza muito pr\u00f3xima do limite do processo o que j\u00e1 \u00e9 preocupante. Vamos lembrar que, o erro mais a incerteza do instrumento \u00e9 igual ou inferior a 1\/3 do crit\u00e9rio de aceita\u00e7\u00e3o do processo. Para melhorar, inclu\u00edmos a linha em laranja representando a incerteza da medi\u00e7\u00e3o do processo e ai temos um grande problema.<\/p>\n\n\n\n<p>Podemos dizer que a incerteza da medi\u00e7\u00e3o \u00e9 a d\u00favida que temos com rela\u00e7\u00e3o ao valor exato do erro do instrumento em fun\u00e7\u00e3o de todas as fontes de incerteza. Chamamos de fontes de incerteza tudo que pode influenciar na medi\u00e7\u00e3o como, dilata\u00e7\u00e3o t\u00e9rmica, diferen\u00e7a de materiais, condi\u00e7\u00f5es ambientes entre medi\u00e7\u00f5es, empuxo do ar entre outros.<\/p>\n\n\n\n<p>A quest\u00e3o no segundo caso \u00e9 que, temos a incerteza do instrumento na mesma \u00e1rea da incerteza do processo do processo, ou seja, n\u00e3o fazemos a menor ideia se, o que esta sendo produzido este dentro do crit\u00e9rio de aceita\u00e7\u00e3o. A &#8220;condi\u00e7\u00e3o ideal seria.&#8221;<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao-1024x341.jpg\" alt=\"\" class=\"wp-image-12102\" style=\"width:546px;height:auto\" srcset=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao-1024x341.jpg 1024w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao-300x100.jpg 300w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao-768x256.jpg 768w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao-1536x512.jpg 1536w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao-600x200.jpg 600w, https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-B-03-Sistema-de-gestao-medicao.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>O caso que colocamos acima \u00e9 apenas uma das a\u00e7\u00f5es que comp\u00f5em a gest\u00e3o de medi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Entre os t\u00f3picos que devem ser tratados em um sistema de gest\u00e3o de medi\u00e7\u00e3o, destacamos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fun\u00e7\u00e3o metrol\u00f3gica;<\/li>\n\n\n\n<li>Objetivos da qualidade;<\/li>\n\n\n\n<li>Pessoal;<\/li>\n\n\n\n<li>Documenta\u00e7\u00e3o;<\/li>\n\n\n\n<li>Softwares de computador;<\/li>\n\n\n\n<li>Instrumentos e equipamentos de medi\u00e7\u00e3o;<\/li>\n\n\n\n<li>Comprova\u00e7\u00e3o metrol\u00f3gica;<\/li>\n\n\n\n<li>Controle e ajuste dos instrumentos de equipamentos;<\/li>\n\n\n\n<li>Processo produtivo;<\/li>\n\n\n\n<li>Incerteza da medi\u00e7\u00e3o;<\/li>\n\n\n\n<li>Rastreabilidade.<\/li>\n<\/ul>\n\n\n\n<p>Agora, respondendo efetivamente a pergunta, qual a import\u00e2ncia do sistema de gest\u00e3o de medi\u00e7\u00e3o?<\/p>\n\n\n\n<p>1- Garantir que os instrumentos de medi\u00e7\u00e3o estejam em perfeito funcionamento realizando medi\u00e7\u00f5es confi\u00e1veis;<br>2- Garantir que, o que esta sendo produzido esteja dentro dos crit\u00e9rios de aceita\u00e7\u00e3o;<br>3- Evitar perdas financeiras em fun\u00e7\u00e3o de produtos n\u00e3o conformes.<\/p>\n\n\n\n<p>Se deseja saber mais ou implantar um sistema de gest\u00e3o de medi\u00e7\u00e3o, <a href=\"https:\/\/auna.com.br\/auna\/contato\/\">entre em contato<\/a>. Ser\u00e1 um prazer te ajudar neste processo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gest\u00e3o metrol\u00f3gica \u00e9 definida na NBR ISO 10012 como o &#8220;conjunto de elementos inter-relacionados e interativos, necess\u00e1rios para obter a comprova\u00e7\u00e3o metrol\u00f3gica e o controle cont\u00ednuo dos processos de medi\u00e7\u00e3o.&#8220; A gest\u00e3o metrol\u00f3gica possui tr\u00eas pilares sendo: 1- Requisitos metrol\u00f3gicos do cliente ou RMC &#8211; Os requisitos metrol\u00f3gicos do cliente est\u00e3o relacionados ao processo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":{"0":"post-12001","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-informacao","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Gest\u00e3o metrol\u00f3gica \u00e9 definida na NBR ISO 10012 como o &#8220;conjunto de elementos inter-relacionados e interativos, necess\u00e1rios para obter a comprova\u00e7\u00e3o metrol\u00f3gica e o controle cont\u00ednuo dos processos de medi\u00e7\u00e3o.&#8220; A gest\u00e3o metrol\u00f3gica possui tr\u00eas pilares sendo: 1- Requisitos metrol\u00f3gicos do cliente ou RMC &#8211; Os requisitos metrol\u00f3gicos do cliente est\u00e3o relacionados ao processo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/\" \/>\n<meta property=\"og:site_name\" content=\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T01:58:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T13:22:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1654\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dep. Comercial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dep. Comercial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/\"},\"author\":{\"name\":\"Dep. Comercial\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/person\\\/19152994cb78b7d9de682ddfbfb0d47b\"},\"headline\":\"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia.\",\"datePublished\":\"2023-12-19T01:58:41+00:00\",\"dateModified\":\"2024-03-02T13:22:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/\"},\"wordCount\":823,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg\",\"articleSection\":[\"Informa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/\",\"name\":\"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg\",\"datePublished\":\"2023-12-19T01:58:41+00:00\",\"dateModified\":\"2024-03-02T13:22:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg\",\"contentUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg\",\"width\":1654,\"height\":1654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/12\\\/18\\\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#website\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\",\"name\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"description\":\"comercial@auna.com.br || +55 15 9 8129-4041\",\"publisher\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\",\"name\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-AUNA_Logo_Transparente.png\",\"contentUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-AUNA_Logo_Transparente.png\",\"width\":960,\"height\":430,\"caption\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/person\\\/19152994cb78b7d9de682ddfbfb0d47b\",\"name\":\"Dep. Comercial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"caption\":\"Dep. Comercial\"},\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","og_description":"Gest\u00e3o metrol\u00f3gica \u00e9 definida na NBR ISO 10012 como o &#8220;conjunto de elementos inter-relacionados e interativos, necess\u00e1rios para obter a comprova\u00e7\u00e3o metrol\u00f3gica e o controle cont\u00ednuo dos processos de medi\u00e7\u00e3o.&#8220; A gest\u00e3o metrol\u00f3gica possui tr\u00eas pilares sendo: 1- Requisitos metrol\u00f3gicos do cliente ou RMC &#8211; Os requisitos metrol\u00f3gicos do cliente est\u00e3o relacionados ao processo de [&hellip;]","og_url":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/","og_site_name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","article_published_time":"2023-12-19T01:58:41+00:00","article_modified_time":"2024-03-02T13:22:30+00:00","og_image":[{"width":1654,"height":1654,"url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg","type":"image\/jpeg"}],"author":"Dep. Comercial","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dep. Comercial","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#article","isPartOf":{"@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/"},"author":{"name":"Dep. Comercial","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/person\/19152994cb78b7d9de682ddfbfb0d47b"},"headline":"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia.","datePublished":"2023-12-19T01:58:41+00:00","dateModified":"2024-03-02T13:22:30+00:00","mainEntityOfPage":{"@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/"},"wordCount":823,"commentCount":0,"publisher":{"@id":"https:\/\/auna.com.br\/auna\/#organization"},"image":{"@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#primaryimage"},"thumbnailUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg","articleSection":["Informa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/","url":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/","name":"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/auna.com.br\/auna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#primaryimage"},"image":{"@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#primaryimage"},"thumbnailUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg","datePublished":"2023-12-19T01:58:41+00:00","dateModified":"2024-03-02T13:22:30+00:00","breadcrumb":{"@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#primaryimage","url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg","contentUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/12\/0022-A-01-Blog-Sistema-de-gestao-de-medicao.jpg","width":1654,"height":1654},{"@type":"BreadcrumbList","@id":"https:\/\/auna.com.br\/auna\/2023\/12\/18\/o-que-e-sistema-de-gestao-metrologico-e-qual-a-sua-importancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/auna.com.br\/auna\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 Sistema de Gest\u00e3o Metrol\u00f3gico e qual a sua import\u00e2ncia."}]},{"@type":"WebSite","@id":"https:\/\/auna.com.br\/auna\/#website","url":"https:\/\/auna.com.br\/auna\/","name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","description":"comercial@auna.com.br || +55 15 9 8129-4041","publisher":{"@id":"https:\/\/auna.com.br\/auna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auna.com.br\/auna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/auna.com.br\/auna\/#organization","name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","url":"https:\/\/auna.com.br\/auna\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/logo\/image\/","url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/cropped-AUNA_Logo_Transparente.png","contentUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/cropped-AUNA_Logo_Transparente.png","width":960,"height":430,"caption":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o"},"image":{"@id":"https:\/\/auna.com.br\/auna\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/person\/19152994cb78b7d9de682ddfbfb0d47b","name":"Dep. Comercial","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","caption":"Dep. Comercial"},"url":"https:\/\/auna.com.br\/auna\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/12001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/comments?post=12001"}],"version-history":[{"count":12,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/12001\/revisions"}],"predecessor-version":[{"id":12110,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/12001\/revisions\/12110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/media\/12109"}],"wp:attachment":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/media?parent=12001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/categories?post=12001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/tags?post=12001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}