{"id":12777,"date":"2024-02-19T08:30:00","date_gmt":"2024-02-19T11:30:00","guid":{"rendered":"https:\/\/auna.com.br\/auna\/?p=12777"},"modified":"2024-03-02T10:23:53","modified_gmt":"2024-03-02T13:23:53","slug":"integracao-de-sistemas-informatizados","status":"publish","type":"post","link":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/","title":{"rendered":"Integra\u00e7\u00e3o de Sistemas Informatizados."},"content":{"rendered":"<p>Quando falamos em automa\u00e7\u00e3o de processo em laborat\u00f3rio, normalmente pensamos em rob\u00f4s pegando amostra de um lado, colocando em outro, evoluindo para outro rob\u00f4 carregando as amostras para o freezer e ainda temos um terceiro fazendo e trazendo caf\u00e9 mas, dificilmente pensamos na automa\u00e7\u00e3o da informa\u00e7\u00e3o a qual nos toma um tempo enorme por n\u00e3o selecionarmos e utilizarmos de forma correta os softwares existentes reduzindo drasticamente nossa produtividade e consequentemente, lucratividade que na verdade \u00e9 o que importa no fim do processo. Dinheiro no bolso.<\/p>\n<p>\u00c9 um fato. Nenhum software ir\u00e1 atender completamente uma empresa o que dir\u00e1 um laborat\u00f3rio que, al\u00e9m de atender as especificidades t\u00e9cnicas dos ensaios, tem que atender aos requisitos espec\u00edficos normativos e executar a\u00e7\u00f5es que garantam os resultados declarados nos relat\u00f3rios de ensaio, ou seja, \u00e9 necess\u00e1rio que o desenvolvedor do software possua um corpo t\u00e9cnico altamente qualificado n\u00e3o s\u00f3 em tecnologia da informa\u00e7\u00e3o mas tamb\u00e9m na especialidade em que se prop\u00f5em a desenvolver o software sendo imposs\u00edvel em fun\u00e7\u00e3o de estrutura, desenvolver um produto que atenda todos os setores da empresa.<\/p>\n<p>Desta forma \u00e9 fundamental que o LIMS utilizado pelo laborat\u00f3rio possa trocar informa\u00e7\u00f5es com outros software possibilitando que a informa\u00e7\u00e3o possa fluir de forma autom\u00e1tica por todos os setores da empresa automatizando todo o processo deixando n\u00f3s, humanos, livres para executar as tarefas de alto n\u00edvel.<\/p>\n<p>Vamos destacar alguns pontos.<\/p>\n<p><strong>1. Efici\u00eancia operacional:<\/strong> A integra\u00e7\u00e3o de softwares permite que diferentes sistemas compartilhem dados de forma autom\u00e1tica e eficiente, eliminando a necessidade de entrada manual de dados em v\u00e1rios sistemas. Isso aumenta a efici\u00eancia operacional, reduzindo erros e redund\u00e2ncias.<\/p>\n<p><strong>2. Tomada de decis\u00e3o baseada em dados:<\/strong> Com a integra\u00e7\u00e3o de softwares, as organiza\u00e7\u00f5es t\u00eam acesso a uma vis\u00e3o mais completa e atualizada de seus dados, o que permite uma tomada de decis\u00e3o mais informada e \u00e1gil principalmente se tiverem as ferramentas de an\u00e1lise correta como, Business Intelligence.<\/p>\n<p><strong>3. Melhoria da experi\u00eancia do cliente:<\/strong> Ao integrar sistemas que lidam com diferentes aspectos do ciclo de vida do cliente, como vendas, marketing e suporte, as empresas podem fornecer uma experi\u00eancia mais integrada e personalizada aos clientes.<\/p>\n<p><strong>4. Flexibilidade e escalabilidade:<\/strong> A integra\u00e7\u00e3o de softwares permite que as organiza\u00e7\u00f5es se adaptem mais facilmente \u00e0s mudan\u00e7as nas necessidades do neg\u00f3cio e escalabilidade \u00e0 medida que crescem, pois os sistemas podem ser facilmente ajustados e expandidos para atender a novos requisitos.<\/p>\n<p><strong>5. Redu\u00e7\u00e3o de custos:<\/strong> Ao automatizar processos e eliminar a necessidade de sistemas isolados e manuais, a integra\u00e7\u00e3o de softwares pode reduzir os custos operacionais e de manuten\u00e7\u00e3o de TI a longo prazo.<\/p>\n<p><strong>6. Conformidade regulat\u00f3ria:<\/strong> Em setores altamente regulamentados, como sa\u00fade e financeiro, a integra\u00e7\u00e3o de softwares pode ajudar as organiza\u00e7\u00f5es a garantir conformidade com regulamentos e padr\u00f5es de seguran\u00e7a, garantindo que os dados sejam gerenciados e protegidos adequadamente.<\/p>\n<p>Em resumo, a integra\u00e7\u00e3o do software LIMS com CRM\u00b4s, ERP\u00b4s, financeiros entre outros \u00e9 essencial para elevar e manter em alto n\u00edvel a produtividade, rastreabilidade, efici\u00eancia, a agilidade e a capacidade do laborat\u00f3rio.<\/p>\n<p>Esse \u00e9 um dos diferenciais do Ultra LIMS, sua capacidade de integra\u00e7\u00e3o com softwares dos mais diversos segmentos possibilitando ao laborat\u00f3rio automatizar todo o processo e mostrar aos gestores as informa\u00e7\u00f5es em tempo real.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando falamos em automa\u00e7\u00e3o de processo em laborat\u00f3rio, normalmente pensamos em rob\u00f4s pegando amostra de um lado, colocando em outro, evoluindo para outro rob\u00f4 carregando as amostras para o freezer e ainda temos um terceiro fazendo e trazendo caf\u00e9 mas, dificilmente pensamos na automa\u00e7\u00e3o da informa\u00e7\u00e3o a qual nos toma um tempo enorme por n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":{"0":"post-12777","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-informacao","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Integra\u00e7\u00e3o de Sistemas Informatizados. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Integra\u00e7\u00e3o de Sistemas Informatizados. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Quando falamos em automa\u00e7\u00e3o de processo em laborat\u00f3rio, normalmente pensamos em rob\u00f4s pegando amostra de um lado, colocando em outro, evoluindo para outro rob\u00f4 carregando as amostras para o freezer e ainda temos um terceiro fazendo e trazendo caf\u00e9 mas, dificilmente pensamos na automa\u00e7\u00e3o da informa\u00e7\u00e3o a qual nos toma um tempo enorme por n\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/\" \/>\n<meta property=\"og:site_name\" content=\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-19T11:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T13:23:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2024\/02\/0031-A-01-Blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1654\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dep. Comercial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dep. Comercial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/\"},\"author\":{\"name\":\"Dep. Comercial\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/person\\\/19152994cb78b7d9de682ddfbfb0d47b\"},\"headline\":\"Integra\u00e7\u00e3o de Sistemas Informatizados.\",\"datePublished\":\"2024-02-19T11:30:00+00:00\",\"dateModified\":\"2024-03-02T13:23:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/\"},\"wordCount\":584,\"publisher\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/0031-A-01-Blog.jpg\",\"articleSection\":[\"Informa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/\",\"name\":\"Integra\u00e7\u00e3o de Sistemas Informatizados. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/0031-A-01-Blog.jpg\",\"datePublished\":\"2024-02-19T11:30:00+00:00\",\"dateModified\":\"2024-03-02T13:23:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/0031-A-01-Blog.jpg\",\"contentUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/0031-A-01-Blog.jpg\",\"width\":1654,\"height\":1654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2024\\\/02\\\/19\\\/integracao-de-sistemas-informatizados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integra\u00e7\u00e3o de Sistemas Informatizados.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#website\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\",\"name\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"description\":\"comercial@auna.com.br || +55 15 9 8129-4041\",\"publisher\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\",\"name\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-AUNA_Logo_Transparente.png\",\"contentUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-AUNA_Logo_Transparente.png\",\"width\":960,\"height\":430,\"caption\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/person\\\/19152994cb78b7d9de682ddfbfb0d47b\",\"name\":\"Dep. Comercial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"caption\":\"Dep. Comercial\"},\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Integra\u00e7\u00e3o de Sistemas Informatizados. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/","og_locale":"pt_BR","og_type":"article","og_title":"Integra\u00e7\u00e3o de Sistemas Informatizados. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","og_description":"Quando falamos em automa\u00e7\u00e3o de processo em laborat\u00f3rio, normalmente pensamos em rob\u00f4s pegando amostra de um lado, colocando em outro, evoluindo para outro rob\u00f4 carregando as amostras para o freezer e ainda temos um terceiro fazendo e trazendo caf\u00e9 mas, dificilmente pensamos na automa\u00e7\u00e3o da informa\u00e7\u00e3o a qual nos toma um tempo enorme por n\u00e3o [&hellip;]","og_url":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/","og_site_name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","article_published_time":"2024-02-19T11:30:00+00:00","article_modified_time":"2024-03-02T13:23:53+00:00","og_image":[{"width":1654,"height":1654,"url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2024\/02\/0031-A-01-Blog.jpg","type":"image\/jpeg"}],"author":"Dep. Comercial","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dep. Comercial","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#article","isPartOf":{"@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/"},"author":{"name":"Dep. Comercial","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/person\/19152994cb78b7d9de682ddfbfb0d47b"},"headline":"Integra\u00e7\u00e3o de Sistemas Informatizados.","datePublished":"2024-02-19T11:30:00+00:00","dateModified":"2024-03-02T13:23:53+00:00","mainEntityOfPage":{"@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/"},"wordCount":584,"publisher":{"@id":"https:\/\/auna.com.br\/auna\/#organization"},"image":{"@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#primaryimage"},"thumbnailUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2024\/02\/0031-A-01-Blog.jpg","articleSection":["Informa\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/","url":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/","name":"Integra\u00e7\u00e3o de Sistemas Informatizados. - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/auna.com.br\/auna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#primaryimage"},"image":{"@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#primaryimage"},"thumbnailUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2024\/02\/0031-A-01-Blog.jpg","datePublished":"2024-02-19T11:30:00+00:00","dateModified":"2024-03-02T13:23:53+00:00","breadcrumb":{"@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#primaryimage","url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2024\/02\/0031-A-01-Blog.jpg","contentUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2024\/02\/0031-A-01-Blog.jpg","width":1654,"height":1654},{"@type":"BreadcrumbList","@id":"https:\/\/auna.com.br\/auna\/2024\/02\/19\/integracao-de-sistemas-informatizados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/auna.com.br\/auna\/"},{"@type":"ListItem","position":2,"name":"Integra\u00e7\u00e3o de Sistemas Informatizados."}]},{"@type":"WebSite","@id":"https:\/\/auna.com.br\/auna\/#website","url":"https:\/\/auna.com.br\/auna\/","name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","description":"comercial@auna.com.br || +55 15 9 8129-4041","publisher":{"@id":"https:\/\/auna.com.br\/auna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auna.com.br\/auna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/auna.com.br\/auna\/#organization","name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","url":"https:\/\/auna.com.br\/auna\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/logo\/image\/","url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/cropped-AUNA_Logo_Transparente.png","contentUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/cropped-AUNA_Logo_Transparente.png","width":960,"height":430,"caption":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o"},"image":{"@id":"https:\/\/auna.com.br\/auna\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/person\/19152994cb78b7d9de682ddfbfb0d47b","name":"Dep. Comercial","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","caption":"Dep. Comercial"},"url":"https:\/\/auna.com.br\/auna\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/12777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/comments?post=12777"}],"version-history":[{"count":1,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/12777\/revisions"}],"predecessor-version":[{"id":12780,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/12777\/revisions\/12780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/media\/12779"}],"wp:attachment":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/media?parent=12777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/categories?post=12777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/tags?post=12777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}