{"id":8391,"date":"2023-03-27T08:30:00","date_gmt":"2023-03-27T11:30:00","guid":{"rendered":"https:\/\/auna.com.br\/auna\/?p=8391"},"modified":"2024-03-02T10:24:55","modified_gmt":"2024-03-02T13:24:55","slug":"qual-a-importancia-da-calibracao","status":"publish","type":"post","link":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/","title":{"rendered":"Qual a import\u00e2ncia da calibra\u00e7\u00e3o?"},"content":{"rendered":"\n<p>A calibra\u00e7\u00e3o \u00e9 um processo essencial para que possamos conhecer o erro indicado por um instrumento de medi\u00e7\u00e3o, ou seja, quando uma balan\u00e7a indicar 50 kg o valor real \u00e9 51 kg, por exemplo.<\/p>\n\n\n\n<p>Conhecendo o erro de medi\u00e7\u00e3o \u00e9 poss\u00edvel comparar com crit\u00e9rios de aceita\u00e7\u00e3o e verificar se mesmo com o erro, podemos considerar como verdadeiro o valor indicado pelo instrumento.<\/p>\n\n\n\n<p>Um ponto que destacamos \u00e9 o fato da obrigatoriedade do instrumento ser enviado para a calibra\u00e7\u00e3o e retornar com erro igual a zero. O processo de calibra\u00e7\u00e3o \u00e9 respons\u00e1vel apenas por determinar o erro do instrumento, simples assim. Normalmente os laborat\u00f3rios de calibra\u00e7\u00e3o ou setores de instrumenta\u00e7\u00e3o acabam por ajustar o instrumento visando reduzir ao m\u00e1ximo seu erro mas mas mesmo assim, o instrumento possui um erro.<\/p>\n\n\n\n<p>Podemos dizer que a calibra\u00e7\u00e3o permite:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Garantir a confiabilidade dos resultados de medi\u00e7\u00e3o. Instrumentos de medi\u00e7\u00e3o descalibrados podem fornecer resultados duvidosos, o que pode levar a erros na tomada de decis\u00e3o, benef\u00edcios financeiros, riscos \u00e0 sa\u00fade e seguran\u00e7a;<\/li>\n\n\n\n<li>Atender a normas e regulamentos;<\/li>\n\n\n\n<li>Reduzir custos e aumentar a efici\u00eancia de processos produtivos.<\/li>\n<\/ol>\n\n\n\n<p>Com isso, \u00e9 extremamente importante que os instrumentos a serem utilizados como padr\u00f5es possuem possuem tr\u00eas caracteristicas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alta exatid\u00e3o;<\/li>\n\n\n\n<li>Repetitividade;<\/li>\n\n\n\n<li>Reprodutibilidade.<\/li>\n<\/ul>\n\n\n\n<p>E por que n\u00e3o o erro baixo? Porque o erro nos conhecemos e \u00e9 corrigido no processo de c\u00e1lculo para determina\u00e7\u00e3o do erro do instrumento que estiver sendo calibrado.<\/p>\n\n\n\n<p>Outro ponto que deve ser observado \u00e9 a tecnologia que o padr\u00e3o possui principalmente ser for utilizado nas calibra\u00e7\u00f5es em campo, ou seja, fora do laborat\u00f3rio. Por motivos \u00f3bvios, quando a calibra\u00e7\u00e3o \u00e9 realizada no campo h\u00e1 ou poder\u00e1 haver, uma grande influ\u00eancia do calor. Com isso, h\u00e1 altera\u00e7\u00e3o dos componentes internos e consequentemente a altera\u00e7\u00e3o do erro conhecido sendo necess\u00e1rio sua corre\u00e7\u00e3o.<\/p>\n\n\n\n<p>O recomendado \u00e9 que, sempre que poss\u00edvel, o instrumento utilizado como padr\u00e3o fa\u00e7a a corre\u00e7\u00e3o autom\u00e1tica do valor  indicado.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Se quiser saber mais, entre em contato ou proponha uma pauta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A calibra\u00e7\u00e3o \u00e9 um processo essencial para que possamos conhecer o erro indicado por um instrumento de medi\u00e7\u00e3o, ou seja, quando uma balan\u00e7a indicar 50 kg o valor real \u00e9 51 kg, por exemplo. Conhecendo o erro de medi\u00e7\u00e3o \u00e9 poss\u00edvel comparar com crit\u00e9rios de aceita\u00e7\u00e3o e verificar se mesmo com o erro, podemos considerar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8566,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":{"0":"post-8391","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-informacao","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qual a import\u00e2ncia da calibra\u00e7\u00e3o? - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a import\u00e2ncia da calibra\u00e7\u00e3o? - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A calibra\u00e7\u00e3o \u00e9 um processo essencial para que possamos conhecer o erro indicado por um instrumento de medi\u00e7\u00e3o, ou seja, quando uma balan\u00e7a indicar 50 kg o valor real \u00e9 51 kg, por exemplo. Conhecendo o erro de medi\u00e7\u00e3o \u00e9 poss\u00edvel comparar com crit\u00e9rios de aceita\u00e7\u00e3o e verificar se mesmo com o erro, podemos considerar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/\" \/>\n<meta property=\"og:site_name\" content=\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T11:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T13:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/2023_0005_Blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1654\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dep. Comercial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dep. Comercial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/\"},\"author\":{\"name\":\"Dep. Comercial\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/person\\\/19152994cb78b7d9de682ddfbfb0d47b\"},\"headline\":\"Qual a import\u00e2ncia da calibra\u00e7\u00e3o?\",\"datePublished\":\"2023-03-27T11:30:00+00:00\",\"dateModified\":\"2024-03-02T13:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023_0005_Blog.jpg\",\"articleSection\":[\"Informa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/\",\"name\":\"Qual a import\u00e2ncia da calibra\u00e7\u00e3o? - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023_0005_Blog.jpg\",\"datePublished\":\"2023-03-27T11:30:00+00:00\",\"dateModified\":\"2024-03-02T13:24:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023_0005_Blog.jpg\",\"contentUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/2023_0005_Blog.jpg\",\"width\":1654,\"height\":1654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/2023\\\/03\\\/27\\\/qual-a-importancia-da-calibracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a import\u00e2ncia da calibra\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#website\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\",\"name\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"description\":\"comercial@auna.com.br || +55 15 9 8129-4041\",\"publisher\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#organization\",\"name\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-AUNA_Logo_Transparente.png\",\"contentUrl\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-AUNA_Logo_Transparente.png\",\"width\":960,\"height\":430,\"caption\":\"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/#\\\/schema\\\/person\\\/19152994cb78b7d9de682ddfbfb0d47b\",\"name\":\"Dep. Comercial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g\",\"caption\":\"Dep. Comercial\"},\"url\":\"https:\\\/\\\/auna.com.br\\\/auna\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a import\u00e2ncia da calibra\u00e7\u00e3o? - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a import\u00e2ncia da calibra\u00e7\u00e3o? - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","og_description":"A calibra\u00e7\u00e3o \u00e9 um processo essencial para que possamos conhecer o erro indicado por um instrumento de medi\u00e7\u00e3o, ou seja, quando uma balan\u00e7a indicar 50 kg o valor real \u00e9 51 kg, por exemplo. Conhecendo o erro de medi\u00e7\u00e3o \u00e9 poss\u00edvel comparar com crit\u00e9rios de aceita\u00e7\u00e3o e verificar se mesmo com o erro, podemos considerar [&hellip;]","og_url":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/","og_site_name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","article_published_time":"2023-03-27T11:30:00+00:00","article_modified_time":"2024-03-02T13:24:55+00:00","og_image":[{"width":1654,"height":1654,"url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/2023_0005_Blog.jpg","type":"image\/jpeg"}],"author":"Dep. Comercial","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dep. Comercial","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#article","isPartOf":{"@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/"},"author":{"name":"Dep. Comercial","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/person\/19152994cb78b7d9de682ddfbfb0d47b"},"headline":"Qual a import\u00e2ncia da calibra\u00e7\u00e3o?","datePublished":"2023-03-27T11:30:00+00:00","dateModified":"2024-03-02T13:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/auna.com.br\/auna\/#organization"},"image":{"@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#primaryimage"},"thumbnailUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/2023_0005_Blog.jpg","articleSection":["Informa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/","url":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/","name":"Qual a import\u00e2ncia da calibra\u00e7\u00e3o? - AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/auna.com.br\/auna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#primaryimage"},"image":{"@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#primaryimage"},"thumbnailUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/2023_0005_Blog.jpg","datePublished":"2023-03-27T11:30:00+00:00","dateModified":"2024-03-02T13:24:55+00:00","breadcrumb":{"@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#primaryimage","url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/2023_0005_Blog.jpg","contentUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/2023_0005_Blog.jpg","width":1654,"height":1654},{"@type":"BreadcrumbList","@id":"https:\/\/auna.com.br\/auna\/2023\/03\/27\/qual-a-importancia-da-calibracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/auna.com.br\/auna\/"},{"@type":"ListItem","position":2,"name":"Qual a import\u00e2ncia da calibra\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/auna.com.br\/auna\/#website","url":"https:\/\/auna.com.br\/auna\/","name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","description":"comercial@auna.com.br || +55 15 9 8129-4041","publisher":{"@id":"https:\/\/auna.com.br\/auna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auna.com.br\/auna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/auna.com.br\/auna\/#organization","name":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o","url":"https:\/\/auna.com.br\/auna\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/logo\/image\/","url":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/cropped-AUNA_Logo_Transparente.png","contentUrl":"https:\/\/auna.com.br\/auna\/wp-content\/uploads\/2023\/03\/cropped-AUNA_Logo_Transparente.png","width":960,"height":430,"caption":"AUNA Metrologia e Instrumenta\u00e7\u00e3o - Instrumentos de Medi\u00e7\u00e3o, Sensores para Monitoramento e Software para Calibra\u00e7\u00e3o, Ensaio e Inspe\u00e7\u00e3o"},"image":{"@id":"https:\/\/auna.com.br\/auna\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/auna.com.br\/auna\/#\/schema\/person\/19152994cb78b7d9de682ddfbfb0d47b","name":"Dep. Comercial","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb2806e752254ae7c3937152a6f59feba9f4a51621d48669cc17178e48012540?s=96&d=mm&r=g","caption":"Dep. Comercial"},"url":"https:\/\/auna.com.br\/auna\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/8391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/comments?post=8391"}],"version-history":[{"count":4,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/8391\/revisions"}],"predecessor-version":[{"id":8565,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/posts\/8391\/revisions\/8565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/media\/8566"}],"wp:attachment":[{"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/media?parent=8391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/categories?post=8391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auna.com.br\/auna\/wp-json\/wp\/v2\/tags?post=8391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}